{"id":2416,"date":"2023-07-06T13:52:23","date_gmt":"2023-07-06T13:52:23","guid":{"rendered":"https:\/\/www.crizia.com.ar\/crizia\/?p=2416"},"modified":"2023-07-06T21:48:45","modified_gmt":"2023-07-06T21:48:45","slug":"tercera-edicion-de-sentidos","status":"publish","type":"post","link":"https:\/\/www.crizia.com.ar\/crizia\/2023\/07\/06\/tercera-edicion-de-sentidos\/","title":{"rendered":"Tercera edici\u00f3n de \u201cSentidos\u201d"},"content":{"rendered":"<p style=\"text-align: center;\">Chef Gabriel Oggero, due\u00f1o de Crizia \/ Sebasti\u00e1n Zuccardi, bodega Zuccardi Valle de Uco \/ Chef Mitsuharu Tsumura, propietario de MAIDO<\/p>\n<p class=\"lead\" style=\"text-align: center;\"><strong>Crizia Restaurante y su chef Gabriel Oggero reciben a Mitsuharu Tsumura<\/strong><\/p>\n<div class=\"row\"  id=\"row-963416634\">\n<div class=\"col medium-6 small-12 large-6\"  ><div class=\"col-inner\"  >\n<p><em>Creada y pensada como un viaje de culturas a trav\u00e9s de los productos y la pasi\u00f3n por la cocina latinoamericana, el pr\u00f3ximo martes 4 de julio <strong>Crizia Restaurante<\/strong> presentar\u00e1 la tercera edici\u00f3n de Sentidos, un ciclo que ofrecer\u00e1 un recorrido culinario \u00fanico.<\/em><\/p>\n<p><em>El Chef <strong>Gabriel Oggero<\/strong>, due\u00f1o de Crizia, y su colega peruano <strong>Mitsuharu Tsumura<\/strong>, multipremiado por su reconocido restaurante de cocina Nikkei, <strong>MAIDO<\/strong>, quien ocupa actualmente el puesto 6 en <strong>The World&#8217;s 50 Best Restaurants 2023<\/strong> estar\u00e1n presentando un men\u00fa de 7 pasos con platos inspirados en\u00a0 sus or\u00edgenes y filosof\u00eda. Junto a la presencia del prestigioso viticultor <strong>Sebasti\u00e1n Zuccardi <\/strong>quien acompa\u00f1ar\u00e1 la velada con una selecci\u00f3n de vinos \u00fanicos de su bodega.<\/em><\/p>\n<p><em>Experiencia que se replicar\u00e1 en la provincia de Mendoza, en el restaurante \u201cPiedra Infinita Cocina\u201d de bodega Zuccardi Valle de Uco, frente a la majestuosa Cordillera de Los Andes, m\u00e1s precisamente en Paraje Altamira, Valle de Uco, el viernes 7 de julio, en un escenario \u00fanico de monta\u00f1a y vi\u00f1edos.<br \/>\n<\/em><br \/>\n<em>Buenos Aires, junio de 2023. Con su ya cl\u00e1sico sello <strong>gourmet<\/strong>, que combina la<strong> cocina de autor<\/strong> con<strong> el dise\u00f1o, la meticulosidad y la creatividad<\/strong> puesta al servicio de la m\u00e1xima expresi\u00f3n de los productos de estaci\u00f3n,<strong> Crizia Restaurante, <\/strong>pr\u00f3ximos a cumplir 19 a\u00f1os,\u00a0 contin\u00faa sorprendiendo y agasajando a los amantes del buen comer en una tercera edici\u00f3n, donde vuelven a ser protagonistas los <strong>sentidos <\/strong>para celebrar la <strong>gastronom\u00eda regional<\/strong>.<\/em><\/p>\n<p><em>En esta ocasi\u00f3n, <strong>Gabriel Oggero<\/strong>, chef ejecutivo de <strong>Crizia<\/strong>, cocinar\u00e1 en t\u00e1ndem con el chef invitado <strong>Mitsuharu Tsumura <\/strong>a cargo del premiado restaurante <strong>MAIDO<\/strong>, de Per\u00fa, reconocido como mejor restaurante en Latinoam\u00e9rica, puesto 1 durante tres a\u00f1os consecutivos en la lista de los Latin America&#8217;s 50 Best Restaurants (2017 &#8211; 2019)<strong>.<\/strong> Actualmente se ubica el Puesto 1 como mejor restaurante de Per\u00fa seg\u00fan la Gu\u00eda SUMMUM, puesto 3 en la lista de los Latin America &#8216;s 50 Best Restaurants y puesto 6 en la lista de <strong>The World&#8217;s 50 Best Restaurants 2023<\/strong>, recientemente otorgado.<\/em><\/p>\n<p><em>M\u00e1s conocido como Micha, se une en esta oportunidad a <strong>Crizia <\/strong>para presentar juntos un <strong>men\u00fa exclusivo y completo <\/strong>de pasos con el sello y la impronta de cada una de estas cocinas junto con la presencia del reconocido viticultor, <strong>Sebasti\u00e1n Zuccardi<\/strong> y sus exquisitos vinos.<\/em><\/p>\n<p><em>Se trata de la tercera edici\u00f3n de <strong>\u201cSentidos\u201d<\/strong>, una experiencia dise\u00f1ada al detalle, en la que cada producto ha sido seleccionado y trabajado especialmente para deleitar a los paladares m\u00e1s exigentes.<\/em><\/p>\n<p><em>La cita es el pr\u00f3ximo <strong>martes 4 de julio<\/strong>, en <strong>Crizia<\/strong> (Fitz Roy 1819, Palermo, CABA), donde los dos grandes chefs elaborar\u00e1n en conjunto exquisitos platos representativos de la <strong>gastronom\u00eda peruana y argentina<\/strong>.<\/em><\/p>\n<p><em>Este evento exclusivo de <strong>Crizia Restaurante<\/strong>, es una propuesta gastron\u00f3mica \u00fanica donde la <strong>experiencia sensorial <\/strong>es el objetivo principal y en esa b\u00fasqueda se fusiona la pasi\u00f3n de dos culturas, dos chefs por la cocina de Latinoam\u00e9rica, en esta ocasi\u00f3n la protagonizar\u00e1n <strong>Gabriel Oggero<\/strong> y <strong>Mitsuharu Tsumura.<\/strong><\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<\/div><\/div>\n<div class=\"col medium-6 small-12 large-6\"  ><div class=\"col-inner\"  >\n<div class=\"row\"  id=\"row-1951429247\">\n<div class=\"col small-12 large-12\"  ><div class=\"col-inner\"  >\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe loading=\"lazy\" title=\"Tercera edici\u00f3n de \u201cSentidos\u201d.\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/1IOCqrUQzQQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<p><em><strong>Per\u00fa y Argentina en una misma cocina<\/strong><\/em><\/p>\n<p><em>Cada uno con su estilo y con la impronta de la cultura de origen, los chefs<strong> Mitsuharu Tsumura <\/strong>y <strong>Gabriel Oggero<\/strong> coinciden en la b\u00fasqueda de poner el producto en su m\u00e1xima expresi\u00f3n y en el trabajo con <strong>ingredientes de temporada<\/strong>, de <strong>calidad <\/strong>y representativos de cada regi\u00f3n mezclando t\u00e9cnicas antiguas y contempor\u00e1neas bas\u00e1ndose en productos de <strong>mar y tierra<\/strong>.<\/em><\/p>\n<p><em>La cocina de <strong>Gabriel Oggero<\/strong> es el resultado de una b\u00fasqueda que abarca toda la Argentina y que resalta el trabajo de los <strong>peque\u00f1os productores<\/strong> con un claro enfoque en la <strong>pesca artesanal<\/strong> y poniendo en valor un recorrido por el <strong>mar argentino<\/strong> y sus productos m\u00e1s destacados. Los fuegos, el grill y el horno a carb\u00f3n y le\u00f1a se destacan en su propuesta.\u00a0 Y desde hace varios a\u00f1os se dedica activamente al desarrollo de las <strong>ostras <\/strong>patag\u00f3nicas, siendo hoy un referente de este producto.<\/em><\/p>\n<p><em>En <strong>Crizia Restaurante<\/strong>, Gabriel despliega sus conocimientos y completa la experiencia gastron\u00f3mica con la arquitectura de <strong>dise\u00f1o <\/strong>en un espacio <strong>moderno, c\u00e1lido e innovador.<\/strong><\/em><\/p>\n<p><em>Por su parte, <strong>Mitsuharu Tsumura<\/strong>, es quiz\u00e1 uno de los mayores exponentes de la comida peruana en el mundo, dirige el restaurante<strong> MAIDO<\/strong>\u00a0 fruto de la pasi\u00f3n de Micha por la comida <strong>Nikkei <\/strong>el cual tiene inspiraci\u00f3n en su pa\u00eds, los paisajes, los insumos y el ingenio del chef.<\/em><\/p>\n<p><em><strong>MAIDO <\/strong>abri\u00f3 sus puertas con un <strong>concepto japon\u00e9s <\/strong>y luego se fue convirtiendo en un restaurante <strong>Nikkei<\/strong> con mucha <strong>influencia peruana<\/strong>.<\/em><\/p>\n<p><em><strong>Nikkei<\/strong>, pues estas son sus ra\u00edces y lo que ofrece nace en su imaginaci\u00f3n, la cual se nutre de sus recuerdos de ni\u00f1o y nuevas vivencias hasta hacerse sabroso.<\/em><\/p>\n<p><em>Los chefs coinciden en la exploraci\u00f3n de <strong>sabores, aromas y texturas<\/strong> a partir de<strong> ingredientes frescos y de alt\u00edsima calidad<\/strong>, mixturando t\u00e9cnicas tradicionales y novedosas y poniendo siempre a los <strong>productos <\/strong>como <strong>protagonistas<\/strong>.<\/em><\/p>\n<p><em>Y ellos mismos idearon un men\u00fa de <strong>7 pasos <\/strong>en donde sus pa\u00edses de origen ofrecen los mejores productos.<\/em><\/p>\n<p><em>Cada paso se ofrece en <strong>maridaje <\/strong>con los vinos de bodega <strong>Zuccardi Valle de Uco<\/strong>, su viticultor <strong>Sebasti\u00e1n Zuccardi<\/strong> junto al equipo de sommeliers de Crizia han realizado una selecci\u00f3n especial, entre los cuales se encuentran: Alma 4 Serie Circular 2012; F\u00f3sil 2021; Bot\u00e1nico 2021; Concreto 2021; Aluvional Gualtallary 2018; Finca Piedra Infinita 2019 y Soler\u00eda, vinos\u00a0 que ser\u00e1n el complemento perfecto para la propuesta de<strong> Sentido<\/strong><strong>s<\/strong>.<\/em><\/p>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Chef Gabriel Oggero, due\u00f1o de Crizia \/ Sebasti\u00e1n Zuccardi, bodega Zuccardi Valle de Uco \/ Chef Mitsuharu Tsumura, propietario de MAIDO Crizia Restaurante y su chef Gabriel Oggero reciben a Mitsuharu Tsumura<\/p>\n","protected":false},"author":8,"featured_media":2421,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":67,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-es"],"_links":{"self":[{"href":"https:\/\/www.crizia.com.ar\/crizia\/wp-json\/wp\/v2\/posts\/2416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crizia.com.ar\/crizia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.crizia.com.ar\/crizia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.crizia.com.ar\/crizia\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.crizia.com.ar\/crizia\/wp-json\/wp\/v2\/comments?post=2416"}],"version-history":[{"count":11,"href":"https:\/\/www.crizia.com.ar\/crizia\/wp-json\/wp\/v2\/posts\/2416\/revisions"}],"predecessor-version":[{"id":2482,"href":"https:\/\/www.crizia.com.ar\/crizia\/wp-json\/wp\/v2\/posts\/2416\/revisions\/2482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crizia.com.ar\/crizia\/wp-json\/wp\/v2\/media\/2421"}],"wp:attachment":[{"href":"https:\/\/www.crizia.com.ar\/crizia\/wp-json\/wp\/v2\/media?parent=2416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.crizia.com.ar\/crizia\/wp-json\/wp\/v2\/categories?post=2416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.crizia.com.ar\/crizia\/wp-json\/wp\/v2\/tags?post=2416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}